{"id":6402,"count":1,"description":"","link":"https:\/\/dustoffthebible.com\/Blog-archive\/tag\/bible-drones\/","name":"bible drones","slug":"bible-drones","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/dustoffthebible.com\/Blog-archive\/wp-json\/wp\/v2\/tags\/6402","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dustoffthebible.com\/Blog-archive\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/dustoffthebible.com\/Blog-archive\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/dustoffthebible.com\/Blog-archive\/wp-json\/wp\/v2\/posts?tags=6402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}