{"id":2348,"count":2,"description":"","link":"https:\/\/dustoffthebible.com\/Blog-archive\/tag\/isaiah-431-7\/","name":"Isaiah 43:1-7","slug":"isaiah-431-7","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/dustoffthebible.com\/Blog-archive\/wp-json\/wp\/v2\/tags\/2348","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dustoffthebible.com\/Blog-archive\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/dustoffthebible.com\/Blog-archive\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/dustoffthebible.com\/Blog-archive\/wp-json\/wp\/v2\/posts?tags=2348"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}