{"id":9084,"date":"2016-08-09T10:48:50","date_gmt":"2016-08-09T14:48:50","guid":{"rendered":"http:\/\/dustoffthebible.com\/wp-content\/uploads\/2016\/08\/Jesus-loves-me-or-knows-me.jpg"},"modified":"2016-08-09T10:49:53","modified_gmt":"2016-08-09T14:49:53","slug":"jesus-loves-me-or-knows-me","status":"inherit","type":"attachment","link":"https:\/\/dustoffthebible.com\/Blog-archive\/2016\/08\/09\/even-more-christian-memes\/jesus-loves-me-or-knows-me\/#main","title":{"rendered":"Jesus loves me or knows me"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-9084","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/dustoffthebible.com\/wp-content\/uploads\/2016\/08\/Jesus-loves-me-or-knows-me.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/dustoffthebible.com\/wp-content\/uploads\/2016\/08\/Jesus-loves-me-or-knows-me-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"Jesus loves me or knows me\" srcset=\"https:\/\/dustoffthebible.com\/wp-content\/uploads\/2016\/08\/Jesus-loves-me-or-knows-me-300x300.jpg 300w, https:\/\/dustoffthebible.com\/wp-content\/uploads\/2016\/08\/Jesus-loves-me-or-knows-me-150x150.jpg 150w, https:\/\/dustoffthebible.com\/wp-content\/uploads\/2016\/08\/Jesus-loves-me-or-knows-me-74x74.jpg 74w, https:\/\/dustoffthebible.com\/wp-content\/uploads\/2016\/08\/Jesus-loves-me-or-knows-me-209x209.jpg 209w, https:\/\/dustoffthebible.com\/wp-content\/uploads\/2016\/08\/Jesus-loves-me-or-knows-me-326x326.jpg 326w, https:\/\/dustoffthebible.com\/wp-content\/uploads\/2016\/08\/Jesus-loves-me-or-knows-me-350x350.jpg 350w, https:\/\/dustoffthebible.com\/wp-content\/uploads\/2016\/08\/Jesus-loves-me-or-knows-me.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Jesus loves me or knows me<\/p>\n"},"caption":{"rendered":"<p>Jesus loves me or knows me<\/p>\n"},"alt_text":"Jesus loves me or knows me","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":640,"height":640,"file":"2016\/08\/Jesus-loves-me-or-knows-me.jpg","sizes":{"thumbnail":{"file":"Jesus-loves-me-or-knows-me-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/dustoffthebible.com\/wp-content\/uploads\/2016\/08\/Jesus-loves-me-or-knows-me-150x150.jpg"},"medium":{"file":"Jesus-loves-me-or-knows-me-300x300.jpg","width":300,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/dustoffthebible.com\/wp-content\/uploads\/2016\/08\/Jesus-loves-me-or-knows-me-300x300.jpg"},"shareaholic-thumbnail":{"file":"Jesus-loves-me-or-knows-me-300x300.jpg","width":300,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/dustoffthebible.com\/wp-content\/uploads\/2016\/08\/Jesus-loves-me-or-knows-me-300x300.jpg"},"shop_thumbnail":{"file":"Jesus-loves-me-or-knows-me-74x74.jpg","width":74,"height":74,"mime_type":"image\/jpeg","source_url":"https:\/\/dustoffthebible.com\/wp-content\/uploads\/2016\/08\/Jesus-loves-me-or-knows-me-74x74.jpg"},"shop_catalog":{"file":"Jesus-loves-me-or-knows-me-209x209.jpg","width":209,"height":209,"mime_type":"image\/jpeg","source_url":"https:\/\/dustoffthebible.com\/wp-content\/uploads\/2016\/08\/Jesus-loves-me-or-knows-me-209x209.jpg"},"shop_single":{"file":"Jesus-loves-me-or-knows-me-326x326.jpg","width":326,"height":326,"mime_type":"image\/jpeg","source_url":"https:\/\/dustoffthebible.com\/wp-content\/uploads\/2016\/08\/Jesus-loves-me-or-knows-me-326x326.jpg"},"schema-featured":{"file":"Jesus-loves-me-or-knows-me-350x350.jpg","width":350,"height":350,"mime_type":"image\/jpeg","source_url":"https:\/\/dustoffthebible.com\/wp-content\/uploads\/2016\/08\/Jesus-loves-me-or-knows-me-350x350.jpg"},"schema-related":{"file":"Jesus-loves-me-or-knows-me-211x150.jpg","width":211,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/dustoffthebible.com\/wp-content\/uploads\/2016\/08\/Jesus-loves-me-or-knows-me-211x150.jpg"},"schema-widgetthumb":{"file":"Jesus-loves-me-or-knows-me-70x60.jpg","width":70,"height":60,"mime_type":"image\/jpeg","source_url":"https:\/\/dustoffthebible.com\/wp-content\/uploads\/2016\/08\/Jesus-loves-me-or-knows-me-70x60.jpg"},"schema-widgetfull":{"file":"Jesus-loves-me-or-knows-me-300x200.jpg","width":300,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/dustoffthebible.com\/wp-content\/uploads\/2016\/08\/Jesus-loves-me-or-knows-me-300x200.jpg"},"schema-slider":{"file":"Jesus-loves-me-or-knows-me-772x350.jpg","width":772,"height":350,"mime_type":"image\/jpeg","source_url":"https:\/\/dustoffthebible.com\/wp-content\/uploads\/2016\/08\/Jesus-loves-me-or-knows-me-772x350.jpg"},"d4p-bbp-thumb":{"file":"Jesus-loves-me-or-knows-me-128x72.jpg","width":128,"height":72,"mime_type":"image\/jpeg","source_url":"https:\/\/dustoffthebible.com\/wp-content\/uploads\/2016\/08\/Jesus-loves-me-or-knows-me-128x72.jpg"},"full":{"file":"Jesus-loves-me-or-knows-me.jpg","width":640,"height":640,"mime_type":"image\/jpeg","source_url":"https:\/\/dustoffthebible.com\/wp-content\/uploads\/2016\/08\/Jesus-loves-me-or-knows-me.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":9076,"source_url":"https:\/\/dustoffthebible.com\/wp-content\/uploads\/2016\/08\/Jesus-loves-me-or-knows-me.jpg","filename":"Jesus-loves-me-or-knows-me.jpg","filesize":85508,"_links":{"self":[{"href":"https:\/\/dustoffthebible.com\/Blog-archive\/wp-json\/wp\/v2\/media\/9084","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dustoffthebible.com\/Blog-archive\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/dustoffthebible.com\/Blog-archive\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/dustoffthebible.com\/Blog-archive\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dustoffthebible.com\/Blog-archive\/wp-json\/wp\/v2\/comments?post=9084"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":9076,"href":"https:\/\/dustoffthebible.com\/Blog-archive\/wp-json\/wp\/v2\/posts\/9076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}