{"id":2515,"count":2,"description":"","link":"https:\/\/dustoffthebible.com\/Blog-archive\/category\/ebooks\/","name":"eBooks","slug":"ebooks","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/dustoffthebible.com\/Blog-archive\/wp-json\/wp\/v2\/categories\/2515","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dustoffthebible.com\/Blog-archive\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/dustoffthebible.com\/Blog-archive\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/dustoffthebible.com\/Blog-archive\/wp-json\/wp\/v2\/posts?categories=2515"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}